{"id":5204,"date":"2026-01-08T09:32:04","date_gmt":"2026-01-08T12:32:04","guid":{"rendered":"https:\/\/solobrasid.com\/porta-corta-fogo\/?p=5204"},"modified":"2026-01-08T20:06:05","modified_gmt":"2026-01-08T23:06:05","slug":"para-de-minas-minas-gerais","status":"publish","type":"post","link":"https:\/\/solobrasid.com\/porta-corta-fogo\/para-de-minas-minas-gerais\/","title":{"rendered":"Porta Corta Fogo &#8211; Par\u00e1 de Minas , Minas Gerais"},"content":{"rendered":"\n\n<h2 class=\"wp-block-heading\">Porta Corta Fogo em Par\u00e1 de Minas ,  Minas Gerais?<\/h2>\n\n\n\n\n\n\n<p class=\"wp-block-paragraph\">Precisando de porta corta fogo em Par\u00e1 de Minas ,  Minas Gerais? Se sim, voc\u00ea veio ao Lugar Certo! Fabrica\u00e7\u00e3o e Venda de Portas Corta Fogo P30, P60, P90, P120 Solicite Or\u00e7amento&nbsp;!<\/p>\n\n\n\n\n\n\n<ul class=\"wp-block-list has-accent-background-color has-background\">\n\n<li><a href=\"#Para-que-serve-a-Porta-Corta-Fogo\">Para que serve a Porta Corta Fogo<\/a><\/li>\n\n\n\n\n\n\n<li><a href=\"#Norma-ABNT-NBR\">Norma ABNT NBR 11742 <\/a><\/li>\n\n\n\n\n\n\n<li><a href=\"#Especifica\u00e7\u00f5es-da-Porta-Corta-Fogo\">Especifica\u00e7\u00f5es da Porta Corta Fogo<\/a><\/li>\n\n\n\n\n\n\n<li><a href=\"#Acess\u00f3rios-Opcionais-da-Porta-Corta-Fogo\">Acess\u00f3rios Opcionais da Porta Corta Fogo<\/a><\/li>\n\n\n\n\n\n\n<li><a href=\"#Modelos-de-Porta-Corta-Fogo\">Modelos de Porta Corta Fogo<\/a><\/li>\n\n\n\n\n\n\n<li><a href=\"#Componentes-do-Conjunto\">Componentes do Conjunto<\/a><\/li>\n\n\n\n\n\n\n<li><a href=\"#Manuten\u00e7\u00e3o-das-Portas-Corta-Fogo-\">Manuten\u00e7\u00e3o das Portas Corta Fogo<\/a><\/li>\n\n\n\n\n\n\n<li><a href=\"#Pre\u00e7o-das-Portas-Corta-Fogo\">Pre\u00e7o das Portas Corta Fogo<\/a><\/li>\n\n<\/ul>\n\n\n\n\n\n\n<h2 class=\"wp-block-heading\" id=\"Para-que-serve-a-Porta-Corta-Fogo\">Para que serve a Porta Corta Fogo ?<\/h2>\n\n\n\n\n\n\n<p class=\"wp-block-paragraph\">Como o nome sugere, as portas corta fogo evitam a propaga\u00e7\u00e3o do fogo.&nbsp;Porta Corta Fogo, tamb\u00e9m pode-se chamar de PCF, s\u00e3o <strong>portas resistes ao fogo<\/strong>, que tem por finalidade formar uma barreira de prote\u00e7\u00e3o contra inc\u00eandios, impedindo o avan\u00e7o do fogo e fuma\u00e7a.<\/p>\n\n\n\n\n\n\n<p class=\"wp-block-paragraph\">As portas corta fogo (PCF) normalmente s\u00e3o utilizadas em \u00e1reas de ref\u00fagio, escadas de emerg\u00eancia de edif\u00edcios, corredores e locais que tenham acesso as rotas de fuga. \u2002\u2002<\/p>\n\n\n\n\n\n\n<h2 class=\"wp-block-heading\" id=\"Norma-ABNT-NBR\">Porta Corta Fogo e a Norma ABNT NBR 11742<\/h2>\n\n\n\n\n\n\n<p class=\"wp-block-paragraph\">As portas corta fogo fabricadas pela SOLOBRASID s\u00e3o feitas de acordo com a Norma ABNT NBR 11742 \u2013 Porta Corta-fogo para Sa\u00eddas de Emerg\u00eancia.<\/p>\n\n\n\n\n\n\n<p class=\"wp-block-paragraph\">Para mais informa\u00e7\u00f5es a respeito da norma, segue o link para leitura do documento:<\/p>\n\n\n\n\n\n\n<p class=\"wp-block-paragraph\">\u279c<a href=\"https:\/\/solobrasid.com\/porta-corta-fogo\/normas-norma-abnt-nbr-porta-corta-fogo-pcf\/\">Norma ABNT NBR 11742 e Outras Relacionadas a PCF<\/a><\/p>\n\n\n\n\n\n\n<h2 class=\"wp-block-heading\" id=\"Especifica\u00e7\u00f5es-da-Porta-Corta-Fogo\">Especifica\u00e7\u00f5es da Porta Corta Fogo <\/h2>\n\n\n\n\n\n\n<p class=\"wp-block-paragraph\">As PCF fabricadas pela SOLOBRASID conta com materiais que seguem rigorosamente a <a href=\"#Norma-ABNT-NBR\">norma ABNT NBR 11742 <\/a>.<\/p>\n\n\n\n\n\n\n<p class=\"wp-block-paragraph\">As portas s\u00e3o fabricadas com chapas galvanizadas, revestidas internamente com material isolante t\u00e9rmico de alta densidade, acompanha 03 (tr\u00eas) dobradi\u00e7as tipo mola por folha e fechadura de sobrepor. <\/p>\n\n\n\n\n\n\n<h2 class=\"wp-block-heading\" id=\"Modelos-de-Porta-Corta-Fogo\">Modelos de Porta Corta Fogo (PCF):<\/h2>\n\n\n\n\n\n\n<p class=\"wp-block-paragraph\">As Portas Corta Fogo disp\u00f5e dos modelos simples e dupla, que variam de acordo com a largura.<\/p>\n\n\n\n\n\n\n<p class=\"wp-block-paragraph\">Contamos com uma linha de portas corta-fogo em conformidade com a <a href=\"#Norma-ABNT-NBR\">norma<\/a>, que permitem maior seguran\u00e7a em caso de inc\u00eandio.&nbsp;Elas s\u00e3o classificadas do <strong>P30<\/strong> ao <strong>P120<\/strong> que \u00e9 o tempo de exposi\u00e7\u00e3o a chama, tornando assim barreira protetora contra o fogo e fuma\u00e7a em caso de inc\u00eandio. <\/p>\n\n\n\n\n\n\n<h3 class=\"wp-block-heading\" id=\"Porta-Corta-Fogo-P30\">Porta Corta Fogo P30<\/h3>\n\n\n\n\n\n\n<p class=\"wp-block-paragraph\">A <strong>porta corta fogo P-30<\/strong> suporta apenas 30 minutos  exposta a chama, ela \u00e9 indicada para casas, apartamentos e edif\u00edcios residenciais. Locais com paredes que possuem resist\u00eancia ao fogo de 60 minutos (CF-60).<\/p>\n\n\n\n\n\n\n<h3 class=\"wp-block-heading\" id=\"Porta-Corta-Fogo-P60\">Porta Corta Fogo P60<\/h3>\n\n\n\n\n\n\n<p class=\"wp-block-paragraph\">A <strong>porta corta fogo P-60<\/strong> suporta at\u00e9 60 minutos  exposta a chama , ela \u00e9 indicada para casas, apartamentos e edif\u00edcios residenciais, edif\u00edcios industriais e comerciais, al\u00e9m do fechamento do acesso das escadas de emerg\u00eancia. Locais com paredes que possuem resist\u00eancia ao fogo de 60 minutos (CF-90) <\/p>\n\n\n\n\n\n\n<h3 class=\"wp-block-heading\">Porta Corta Fogo P90<\/h3>\n\n\n\n\n\n\n<p class=\"wp-block-paragraph\">A <strong><a href=\"https:\/\/solobrasid.com\/porta-corta-fogo-p90\/para-de-minas-minas-gerais\/\" rel=\"dofollow\" title=\"Porta Corta Fogo P-90 para de minas minas gerais\">Porta Corta Fogo P-90<\/a><\/strong> suporta at\u00e9 90 minutos  exposta a chama , ela \u00e9 indicada para ind\u00fastrias e locais com alta tens\u00e3o de energia el\u00e9trica. Locais com paredes que possuem resist\u00eancia ao fogo de 60 minutos (CF-180).<\/p>\n\n\n\n\n\n\n<h3 class=\"wp-block-heading\">Porta Corta Fogo P120<\/h3>\n\n\n\n\n\n\n<p class=\"wp-block-paragraph\">A <strong><a href=\"https:\/\/solobrasid.com\/porta-corta-fogo-p120\/para-de-minas-minas-gerais\/\" rel=\"dofollow\" title=\"Porta Corta Fogo P-120 para de minas minas gerais\">Porta Corta Fogo P-120<\/a><\/strong> suporta at\u00e9 120 minutos exposta a chama. <\/p>\n\n\n\n\n\n\n<h4 class=\"wp-block-heading\">Medidas das Portas Corta Fogo Simples:<\/h4>\n\n\n\n\n<div class=\"wp-block-image\">\n\n<figure class=\"aligncenter size-full\"><img loading=\"lazy\" decoding=\"async\" width=\"300\" height=\"300\" src=\"https:\/\/solobrasid.com\/porta-corta-fogo\/wp-content\/uploads\/sites\/3\/2021\/08\/porta-corta-fogo-simples-p30-p60-p90-p120-1.jpg\" alt=\"porta corta fogo simples p30 p60 p90 p120\" class=\"wp-image-6509\" srcset=\"https:\/\/solobrasid.com\/porta-corta-fogo\/wp-content\/uploads\/sites\/3\/2021\/08\/porta-corta-fogo-simples-p30-p60-p90-p120-1.jpg 300w, https:\/\/solobrasid.com\/porta-corta-fogo\/wp-content\/uploads\/sites\/3\/2021\/08\/porta-corta-fogo-simples-p30-p60-p90-p120-1-150x150.jpg 150w\" sizes=\"auto, (max-width: 300px) 100vw, 300px\" \/><\/figure>\n\n<\/div>\n\n\n\n\n<p class=\"wp-block-paragraph\">Tabela de medidas das portas corta fogo simples (PCF):<\/p>\n\n\n\n\n\n\n<figure class=\"wp-block-table is-style-regular\"><table><tbody><tr><td><strong>Largura da Porta:<\/strong><\/td><td><strong>Altura da Porta:<\/strong><\/td><\/tr><tr><td>0,80M &#8211; 800mm<\/td><td>2,10M  &#8211; 2100mm <\/td><\/tr><tr><td>0,90M &#8211; 900mm<\/td><td>2,10M  &#8211; 2100mm <\/td><\/tr><tr><td>1M &#8211; 1000mm<\/td><td>2,10M  &#8211; 2100mm <\/td><\/tr><\/tbody><\/table><\/figure>\n\n\n\n\n\n\n<h4 class=\"wp-block-heading\">Medidas das Porta Corta Fogo Dupla :<\/h4>\n\n\n\n\n<div class=\"wp-block-image\">\n\n<figure class=\"aligncenter size-full\"><img loading=\"lazy\" decoding=\"async\" width=\"219\" height=\"278\" src=\"https:\/\/solobrasid.com\/porta-corta-fogo\/wp-content\/uploads\/sites\/3\/2021\/08\/porta-corta-fogo-dupla-p30-p60-p90-p120-1.jpg\" alt=\"Porta Corta Fogo Dupla\" class=\"wp-image-6510\" \/><\/figure>\n\n<\/div>\n\n\n\n\n<p class=\"wp-block-paragraph\"> Tabela de medidas das portas corta fogo dupla (PCF): <\/p>\n\n\n\n\n\n\n<figure class=\"wp-block-table\"><table><tbody><tr><td><strong>Largura da Porta Dupla<\/strong>:<\/td><td><strong>Altura da Porta Dupla:<\/strong><\/td><\/tr><tr><td>1,60M &#8211; 1600mm<\/td><td>2,10M &#8211; 2100mm<\/td><\/tr><tr><td>1,80M &#8211; 1800mm<\/td><td>2,10M &#8211; 2100mm <\/td><\/tr><tr><td>2,00M &#8211; 2000mm<\/td><td>2,10M &#8211; 2100mm <\/td><\/tr><\/tbody><\/table><\/figure>\n\n\n\n\n\n\n<h2 class=\"wp-block-heading\" id=\"Componentes-do-Conjunto\">Componentes do Conjunto <\/h2>\n\n\n\n\n\n\n<p class=\"wp-block-paragraph\">As Portas Corta Fogo fabricadas pela SOLOBRASID seguir\u00e1 com os seguintes componentes:<\/p>\n\n\n\n\n\n\n<p class=\"wp-block-paragraph\">\u2714\ufe0f1 batente<br>\u2714\ufe0f1 folha (ou 2 folhas caso seja dupla)<br>\u2714\ufe0f3 dobradi\u00e7as<br>\u2714\ufe0f1 fechadura<br>\u2714\ufe0f1 etiqueta<br>Barra anti-p\u00e2nico <strong>(opcional \u2013 vendida separadamente)<\/strong> &#8211; <strong>(Consulte)<\/strong><br>O batente de chapa galvanizada e pesa aproximadamente 11 kg<br>As portas com 2,10 x 0,89M, P-60 e P-90, pesam entre 40 e 66 kg.<\/p>\n\n\n\n\n\n\n<h2 class=\"wp-block-heading\" id=\"Manuten\u00e7\u00e3o-das-Portas-Corta-Fogo-\">Reforma e Manuten\u00e7\u00e3o das Portas Corta Fogo (Servi\u00e7os limitados ao Estado de SP)*<\/h2>\n\n\n\n\n\n\n<p class=\"wp-block-paragraph\">De acordo com a Norma, a manuten\u00e7\u00e3o deve ser responsabilidade do s\u00edndico ou administrador da edifica\u00e7\u00e3o.<\/p>\n\n\n\n\n\n\n<p class=\"wp-block-paragraph\">Voc\u00ea pode contar com a SOLOBRASID para realizar uma <strong>reforma ou manuten\u00e7\u00e3o em sua porta corta fogo<\/strong> , atendemos os seguintes servi\u00e7os:<\/p>\n\n\n\n\n\n\n<ul class=\"wp-block-list\">\n\n<li>Substitui\u00e7\u00e3o das chapas<\/li>\n\n\n\n\n\n\n<li>Troca de batentes<\/li>\n\n\n\n\n\n\n<li>Substitui\u00e7\u00e3o de dobradi\u00e7as<\/li>\n\n\n\n\n\n\n<li>fechaduras <\/li>\n\n\n\n\n\n\n<li>Instala\u00e7\u00e3o de barra anti-p\u00e2nico<\/li>\n\n<\/ul>\n\n\n\n\n\n\n<p class=\"wp-block-paragraph\"><em>*Estes servi\u00e7os s\u00e3o oferecidos exclusivamente no Estado de S\u00e3o Paulo. As portas podem ser enviadas para as devidas manuten\u00e7\u00f5es conforme necess\u00e1rio.<\/em><\/p>\n\n\n\n\n\n\n<h2 class=\"wp-block-heading\" id=\"Acess\u00f3rios-Opcionais-da-Porta-Corta-Fogo\">Acess\u00f3rios Opcionais da Porta Corta Fogo <\/h2>\n\n\n\n\n\n\n<p class=\"wp-block-paragraph\">Alguns exemplos de acess\u00f3rios opcionais para Porta Corta Fogo (PCF)<\/p>\n\n\n\n\n\n\n<ul class=\"wp-block-list\">\n\n<li>Barra Anti- P\u00e2nico<\/li>\n\n\n\n\n\n\n<li>Fechadura de sobrepor<\/li>\n\n\n\n\n\n\n<li>Trava Magn\u00e9tica (eletro im\u00e3)<\/li>\n\n\n\n\n\n\n<li>Mola a\u00e9rea hidr\u00e1ulica \/ Dorma <\/li>\n\n<\/ul>\n\n\n\n\n\n\n<figure class=\"wp-block-gallery has-nested-images columns-5 is-cropped is-style-tw-img-rounded wp-block-gallery-1 is-layout-flex wp-block-gallery-is-layout-flex\">\n\n<figure class=\"wp-block-image size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"300\" height=\"300\" src=\"https:\/\/solobrasid.com\/porta-corta-fogo\/wp-content\/uploads\/sites\/3\/2021\/08\/trava-anti-panico-porta-corta-fogo-1.jpg\" alt=\"\" class=\"wp-image-6516\" srcset=\"https:\/\/solobrasid.com\/porta-corta-fogo\/wp-content\/uploads\/sites\/3\/2021\/08\/trava-anti-panico-porta-corta-fogo-1.jpg 300w, https:\/\/solobrasid.com\/porta-corta-fogo\/wp-content\/uploads\/sites\/3\/2021\/08\/trava-anti-panico-porta-corta-fogo-1-150x150.jpg 150w\" sizes=\"auto, (max-width: 300px) 100vw, 300px\" \/><\/figure>\n\n\n\n\n\n\n<figure class=\"wp-block-image size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"300\" height=\"300\" src=\"https:\/\/solobrasid.com\/porta-corta-fogo\/wp-content\/uploads\/sites\/3\/2021\/08\/fechadura-sobrepor-porta-corta-fogo-sem-chave-1-1.jpg\" alt=\"\" class=\"wp-image-6515\" srcset=\"https:\/\/solobrasid.com\/porta-corta-fogo\/wp-content\/uploads\/sites\/3\/2021\/08\/fechadura-sobrepor-porta-corta-fogo-sem-chave-1-1.jpg 300w, https:\/\/solobrasid.com\/porta-corta-fogo\/wp-content\/uploads\/sites\/3\/2021\/08\/fechadura-sobrepor-porta-corta-fogo-sem-chave-1-1-150x150.jpg 150w\" sizes=\"auto, (max-width: 300px) 100vw, 300px\" \/><\/figure>\n\n\n\n\n\n\n<figure class=\"wp-block-image size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"300\" height=\"300\" src=\"https:\/\/solobrasid.com\/porta-corta-fogo\/wp-content\/uploads\/sites\/3\/2021\/08\/fechadura-eletroima-magnetica-porta-corta-fogo-1.jpg\" alt=\"\" class=\"wp-image-6514\" srcset=\"https:\/\/solobrasid.com\/porta-corta-fogo\/wp-content\/uploads\/sites\/3\/2021\/08\/fechadura-eletroima-magnetica-porta-corta-fogo-1.jpg 300w, https:\/\/solobrasid.com\/porta-corta-fogo\/wp-content\/uploads\/sites\/3\/2021\/08\/fechadura-eletroima-magnetica-porta-corta-fogo-1-150x150.jpg 150w\" sizes=\"auto, (max-width: 300px) 100vw, 300px\" \/><\/figure>\n\n\n\n\n\n\n<figure class=\"wp-block-image size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"300\" height=\"300\" src=\"https:\/\/solobrasid.com\/porta-corta-fogo\/wp-content\/uploads\/sites\/3\/2021\/08\/dorma_mola_aerea_porta-corta-fogo-1.png\" alt=\"\" class=\"wp-image-6513\" srcset=\"https:\/\/solobrasid.com\/porta-corta-fogo\/wp-content\/uploads\/sites\/3\/2021\/08\/dorma_mola_aerea_porta-corta-fogo-1.png 300w, https:\/\/solobrasid.com\/porta-corta-fogo\/wp-content\/uploads\/sites\/3\/2021\/08\/dorma_mola_aerea_porta-corta-fogo-1-150x150.png 150w\" sizes=\"auto, (max-width: 300px) 100vw, 300px\" \/><\/figure>\n\n\n\n\n\n\n<figure class=\"wp-block-image size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"300\" height=\"300\" src=\"https:\/\/solobrasid.com\/porta-corta-fogo\/wp-content\/uploads\/sites\/3\/2021\/08\/dobradica-com-mola-porta-corta-fogo-1.jpg\" alt=\"\" class=\"wp-image-6512\" srcset=\"https:\/\/solobrasid.com\/porta-corta-fogo\/wp-content\/uploads\/sites\/3\/2021\/08\/dobradica-com-mola-porta-corta-fogo-1.jpg 300w, https:\/\/solobrasid.com\/porta-corta-fogo\/wp-content\/uploads\/sites\/3\/2021\/08\/dobradica-com-mola-porta-corta-fogo-1-150x150.jpg 150w\" sizes=\"auto, (max-width: 300px) 100vw, 300px\" \/><\/figure>\n\n<\/figure>\n\n\n\n\n\n\n<p class=\"wp-block-paragraph\">Para outros Acess\u00f3rios opcionais e cores por gentileza entre em contato.<\/p>\n\n\n\n\n\n\n<h2 class=\"wp-block-heading\" id=\"Pre\u00e7o-das-Portas-Corta-Fogo\">Pre\u00e7o das Portas Corta Fogo <\/h2>\n\n\n\n\n\n\n<p class=\"wp-block-paragraph\">Para saber pre\u00e7o das Portas Corta Fogo por favor entre em <a href=\"https:\/\/solobrasid.com\/contato\/\">contato conosco e solicite or\u00e7amento e solicite uma cota\u00e7\u00e3o.<\/a><\/p>\n\n","protected":false},"excerpt":{"rendered":"<p>Porta Corta Fogo &#8211; Par\u00e1 de Minas Minas Gerais Porta Corta Fogo: Simples e Dupla &#8211; P30, P60, P90, P120 \u2714\ufe0f Saiba Pre\u00e7o &#8211; Solicite Or\u00e7amento da PCF ! \u2714\ufe0fValores e Vantagens.<\/p>\n","protected":false},"author":1,"featured_media":5216,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[6,3,4,5],"tags":[],"class_list":["post-5204","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-porta-corta-fogo-p120","category-porta-corta-fogo-p30","category-porta-corta-fogo-p60","category-porta-corta-fogo-p90"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.4 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Porta Corta Fogo - Par\u00e1 de Minas Minas Gerais | SOLOBRASID<\/title>\n<meta name=\"description\" content=\"Porta Corta Fogo - Par\u00e1 de Minas Minas Gerais Porta Corta Fogo: Simples e Dupla - P30, P60, P90, P120 \u2714\ufe0f Saiba Pre\u00e7o - Solicite Or\u00e7amento da PCF ! \u2714\ufe0fValores e Vantagens.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/solobrasid.com\/porta-corta-fogo\/para-de-minas-minas-gerais\/\" \/>\n<meta property=\"og:locale\" content=\"pt_BR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Porta Corta Fogo - Par\u00e1 de Minas Minas Gerais | SOLOBRASID\" \/>\n<meta property=\"og:description\" content=\"Porta Corta Fogo - Par\u00e1 de Minas Minas Gerais Porta Corta Fogo: Simples e Dupla - P30, P60, P90, P120 \u2714\ufe0f Saiba Pre\u00e7o - Solicite Or\u00e7amento da PCF ! \u2714\ufe0fValores e Vantagens.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/solobrasid.com\/porta-corta-fogo\/para-de-minas-minas-gerais\/\" \/>\n<meta property=\"og:site_name\" content=\"SOLOBRASID\" \/>\n<meta property=\"article:published_time\" content=\"2026-01-08T12:32:04+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2026-01-08T23:06:05+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/solobrasid.com\/porta-corta-fogo\/wp-content\/uploads\/sites\/3\/2021\/08\/PORTA-CORTA-FOGO-SOLOBRASID.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1200\" \/>\n\t<meta property=\"og:image:height\" content=\"703\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"solobrasil2\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"solobrasil2\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. tempo de leitura\" \/>\n\t<meta name=\"twitter:data2\" content=\"4 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/solobrasid.com\\\/porta-corta-fogo\\\/para-de-minas-minas-gerais\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/solobrasid.com\\\/porta-corta-fogo\\\/para-de-minas-minas-gerais\\\/\"},\"author\":{\"name\":\"solobrasil2\",\"@id\":\"https:\\\/\\\/solobrasid.com\\\/porta-corta-fogo\\\/#\\\/schema\\\/person\\\/21d4e99588acb49754e89f2bcd9560ff\"},\"headline\":\"Porta Corta Fogo &#8211; Par\u00e1 de Minas , Minas Gerais\",\"datePublished\":\"2026-01-08T12:32:04+00:00\",\"dateModified\":\"2026-01-08T23:06:05+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/solobrasid.com\\\/porta-corta-fogo\\\/para-de-minas-minas-gerais\\\/\"},\"wordCount\":828,\"publisher\":{\"@id\":\"https:\\\/\\\/solobrasid.com\\\/porta-corta-fogo\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/solobrasid.com\\\/porta-corta-fogo\\\/para-de-minas-minas-gerais\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/solobrasid.com\\\/porta-corta-fogo\\\/wp-content\\\/uploads\\\/sites\\\/3\\\/2021\\\/08\\\/PORTA-CORTA-FOGO-SOLOBRASID.jpg\",\"articleSection\":[\"Porta Corta Fogo P120\",\"Porta Corta Fogo P30\",\"Porta Corta Fogo P60\",\"Porta Corta Fogo P90\"],\"inLanguage\":\"pt-BR\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/solobrasid.com\\\/porta-corta-fogo\\\/para-de-minas-minas-gerais\\\/\",\"url\":\"https:\\\/\\\/solobrasid.com\\\/porta-corta-fogo\\\/para-de-minas-minas-gerais\\\/\",\"name\":\"Porta Corta Fogo - Par\u00e1 de Minas Minas Gerais | SOLOBRASID\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/solobrasid.com\\\/porta-corta-fogo\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/solobrasid.com\\\/porta-corta-fogo\\\/para-de-minas-minas-gerais\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/solobrasid.com\\\/porta-corta-fogo\\\/para-de-minas-minas-gerais\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/solobrasid.com\\\/porta-corta-fogo\\\/wp-content\\\/uploads\\\/sites\\\/3\\\/2021\\\/08\\\/PORTA-CORTA-FOGO-SOLOBRASID.jpg\",\"datePublished\":\"2026-01-08T12:32:04+00:00\",\"dateModified\":\"2026-01-08T23:06:05+00:00\",\"description\":\"Porta Corta Fogo - Par\u00e1 de Minas Minas Gerais Porta Corta Fogo: Simples e Dupla - P30, P60, P90, P120 \u2714\ufe0f Saiba Pre\u00e7o - Solicite Or\u00e7amento da PCF ! \u2714\ufe0fValores e Vantagens.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/solobrasid.com\\\/porta-corta-fogo\\\/para-de-minas-minas-gerais\\\/#breadcrumb\"},\"inLanguage\":\"pt-BR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/solobrasid.com\\\/porta-corta-fogo\\\/para-de-minas-minas-gerais\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\\\/\\\/solobrasid.com\\\/porta-corta-fogo\\\/para-de-minas-minas-gerais\\\/#primaryimage\",\"url\":\"https:\\\/\\\/solobrasid.com\\\/porta-corta-fogo\\\/wp-content\\\/uploads\\\/sites\\\/3\\\/2021\\\/08\\\/PORTA-CORTA-FOGO-SOLOBRASID.jpg\",\"contentUrl\":\"https:\\\/\\\/solobrasid.com\\\/porta-corta-fogo\\\/wp-content\\\/uploads\\\/sites\\\/3\\\/2021\\\/08\\\/PORTA-CORTA-FOGO-SOLOBRASID.jpg\",\"width\":1200,\"height\":703,\"caption\":\"Porta Corta Fogo\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/solobrasid.com\\\/porta-corta-fogo\\\/para-de-minas-minas-gerais\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"In\u00edcio\",\"item\":\"https:\\\/\\\/solobrasid.com\\\/porta-corta-fogo\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Porta Corta Fogo &#8211; Par\u00e1 de Minas , Minas Gerais\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/solobrasid.com\\\/porta-corta-fogo\\\/#website\",\"url\":\"https:\\\/\\\/solobrasid.com\\\/porta-corta-fogo\\\/\",\"name\":\"SOLOBRASID\",\"description\":\"Fabrica\u00e7\u00e3o e venda de portas corta fogo sob medida, oferecendo solu\u00e7\u00f5es personalizadas para atender \u00e0s suas necessidades! Portas corta fogo P120, P30, P60 e P90.\",\"publisher\":{\"@id\":\"https:\\\/\\\/solobrasid.com\\\/porta-corta-fogo\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/solobrasid.com\\\/porta-corta-fogo\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"pt-BR\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/solobrasid.com\\\/porta-corta-fogo\\\/#organization\",\"name\":\"SOLOBRASID\",\"url\":\"https:\\\/\\\/solobrasid.com\\\/porta-corta-fogo\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\\\/\\\/solobrasid.com\\\/porta-corta-fogo\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/solobrasid.com\\\/porta-corta-fogo\\\/wp-content\\\/uploads\\\/sites\\\/3\\\/2021\\\/08\\\/SOLOBRASID.png\",\"contentUrl\":\"https:\\\/\\\/solobrasid.com\\\/porta-corta-fogo\\\/wp-content\\\/uploads\\\/sites\\\/3\\\/2021\\\/08\\\/SOLOBRASID.png\",\"width\":1073,\"height\":232,\"caption\":\"SOLOBRASID\"},\"image\":{\"@id\":\"https:\\\/\\\/solobrasid.com\\\/porta-corta-fogo\\\/#\\\/schema\\\/logo\\\/image\\\/\"}},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/solobrasid.com\\\/porta-corta-fogo\\\/#\\\/schema\\\/person\\\/21d4e99588acb49754e89f2bcd9560ff\",\"name\":\"solobrasil2\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/bd8737297dedc53a4b9fb9fec8d3bba36ef88345e3494ce79ce9441c5442504b?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/bd8737297dedc53a4b9fb9fec8d3bba36ef88345e3494ce79ce9441c5442504b?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/bd8737297dedc53a4b9fb9fec8d3bba36ef88345e3494ce79ce9441c5442504b?s=96&d=mm&r=g\",\"caption\":\"solobrasil2\"},\"sameAs\":[\"https:\\\/\\\/solobrasid.com\"]}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Porta Corta Fogo - Par\u00e1 de Minas Minas Gerais | SOLOBRASID","description":"Porta Corta Fogo - Par\u00e1 de Minas Minas Gerais Porta Corta Fogo: Simples e Dupla - P30, P60, P90, P120 \u2714\ufe0f Saiba Pre\u00e7o - Solicite Or\u00e7amento da PCF ! \u2714\ufe0fValores e Vantagens.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/solobrasid.com\/porta-corta-fogo\/para-de-minas-minas-gerais\/","og_locale":"pt_BR","og_type":"article","og_title":"Porta Corta Fogo - Par\u00e1 de Minas Minas Gerais | SOLOBRASID","og_description":"Porta Corta Fogo - Par\u00e1 de Minas Minas Gerais Porta Corta Fogo: Simples e Dupla - P30, P60, P90, P120 \u2714\ufe0f Saiba Pre\u00e7o - Solicite Or\u00e7amento da PCF ! \u2714\ufe0fValores e Vantagens.","og_url":"https:\/\/solobrasid.com\/porta-corta-fogo\/para-de-minas-minas-gerais\/","og_site_name":"SOLOBRASID","article_published_time":"2026-01-08T12:32:04+00:00","article_modified_time":"2026-01-08T23:06:05+00:00","og_image":[{"width":1200,"height":703,"url":"https:\/\/solobrasid.com\/porta-corta-fogo\/wp-content\/uploads\/sites\/3\/2021\/08\/PORTA-CORTA-FOGO-SOLOBRASID.jpg","type":"image\/jpeg"}],"author":"solobrasil2","twitter_card":"summary_large_image","twitter_misc":{"Escrito por":"solobrasil2","Est. tempo de leitura":"4 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/solobrasid.com\/porta-corta-fogo\/para-de-minas-minas-gerais\/#article","isPartOf":{"@id":"https:\/\/solobrasid.com\/porta-corta-fogo\/para-de-minas-minas-gerais\/"},"author":{"name":"solobrasil2","@id":"https:\/\/solobrasid.com\/porta-corta-fogo\/#\/schema\/person\/21d4e99588acb49754e89f2bcd9560ff"},"headline":"Porta Corta Fogo &#8211; Par\u00e1 de Minas , Minas Gerais","datePublished":"2026-01-08T12:32:04+00:00","dateModified":"2026-01-08T23:06:05+00:00","mainEntityOfPage":{"@id":"https:\/\/solobrasid.com\/porta-corta-fogo\/para-de-minas-minas-gerais\/"},"wordCount":828,"publisher":{"@id":"https:\/\/solobrasid.com\/porta-corta-fogo\/#organization"},"image":{"@id":"https:\/\/solobrasid.com\/porta-corta-fogo\/para-de-minas-minas-gerais\/#primaryimage"},"thumbnailUrl":"https:\/\/solobrasid.com\/porta-corta-fogo\/wp-content\/uploads\/sites\/3\/2021\/08\/PORTA-CORTA-FOGO-SOLOBRASID.jpg","articleSection":["Porta Corta Fogo P120","Porta Corta Fogo P30","Porta Corta Fogo P60","Porta Corta Fogo P90"],"inLanguage":"pt-BR"},{"@type":"WebPage","@id":"https:\/\/solobrasid.com\/porta-corta-fogo\/para-de-minas-minas-gerais\/","url":"https:\/\/solobrasid.com\/porta-corta-fogo\/para-de-minas-minas-gerais\/","name":"Porta Corta Fogo - Par\u00e1 de Minas Minas Gerais | SOLOBRASID","isPartOf":{"@id":"https:\/\/solobrasid.com\/porta-corta-fogo\/#website"},"primaryImageOfPage":{"@id":"https:\/\/solobrasid.com\/porta-corta-fogo\/para-de-minas-minas-gerais\/#primaryimage"},"image":{"@id":"https:\/\/solobrasid.com\/porta-corta-fogo\/para-de-minas-minas-gerais\/#primaryimage"},"thumbnailUrl":"https:\/\/solobrasid.com\/porta-corta-fogo\/wp-content\/uploads\/sites\/3\/2021\/08\/PORTA-CORTA-FOGO-SOLOBRASID.jpg","datePublished":"2026-01-08T12:32:04+00:00","dateModified":"2026-01-08T23:06:05+00:00","description":"Porta Corta Fogo - Par\u00e1 de Minas Minas Gerais Porta Corta Fogo: Simples e Dupla - P30, P60, P90, P120 \u2714\ufe0f Saiba Pre\u00e7o - Solicite Or\u00e7amento da PCF ! \u2714\ufe0fValores e Vantagens.","breadcrumb":{"@id":"https:\/\/solobrasid.com\/porta-corta-fogo\/para-de-minas-minas-gerais\/#breadcrumb"},"inLanguage":"pt-BR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/solobrasid.com\/porta-corta-fogo\/para-de-minas-minas-gerais\/"]}]},{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/solobrasid.com\/porta-corta-fogo\/para-de-minas-minas-gerais\/#primaryimage","url":"https:\/\/solobrasid.com\/porta-corta-fogo\/wp-content\/uploads\/sites\/3\/2021\/08\/PORTA-CORTA-FOGO-SOLOBRASID.jpg","contentUrl":"https:\/\/solobrasid.com\/porta-corta-fogo\/wp-content\/uploads\/sites\/3\/2021\/08\/PORTA-CORTA-FOGO-SOLOBRASID.jpg","width":1200,"height":703,"caption":"Porta Corta Fogo"},{"@type":"BreadcrumbList","@id":"https:\/\/solobrasid.com\/porta-corta-fogo\/para-de-minas-minas-gerais\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"In\u00edcio","item":"https:\/\/solobrasid.com\/porta-corta-fogo\/"},{"@type":"ListItem","position":2,"name":"Porta Corta Fogo &#8211; Par\u00e1 de Minas , Minas Gerais"}]},{"@type":"WebSite","@id":"https:\/\/solobrasid.com\/porta-corta-fogo\/#website","url":"https:\/\/solobrasid.com\/porta-corta-fogo\/","name":"SOLOBRASID","description":"Fabrica\u00e7\u00e3o e venda de portas corta fogo sob medida, oferecendo solu\u00e7\u00f5es personalizadas para atender \u00e0s suas necessidades! Portas corta fogo P120, P30, P60 e P90.","publisher":{"@id":"https:\/\/solobrasid.com\/porta-corta-fogo\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/solobrasid.com\/porta-corta-fogo\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"pt-BR"},{"@type":"Organization","@id":"https:\/\/solobrasid.com\/porta-corta-fogo\/#organization","name":"SOLOBRASID","url":"https:\/\/solobrasid.com\/porta-corta-fogo\/","logo":{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/solobrasid.com\/porta-corta-fogo\/#\/schema\/logo\/image\/","url":"https:\/\/solobrasid.com\/porta-corta-fogo\/wp-content\/uploads\/sites\/3\/2021\/08\/SOLOBRASID.png","contentUrl":"https:\/\/solobrasid.com\/porta-corta-fogo\/wp-content\/uploads\/sites\/3\/2021\/08\/SOLOBRASID.png","width":1073,"height":232,"caption":"SOLOBRASID"},"image":{"@id":"https:\/\/solobrasid.com\/porta-corta-fogo\/#\/schema\/logo\/image\/"}},{"@type":"Person","@id":"https:\/\/solobrasid.com\/porta-corta-fogo\/#\/schema\/person\/21d4e99588acb49754e89f2bcd9560ff","name":"solobrasil2","image":{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/secure.gravatar.com\/avatar\/bd8737297dedc53a4b9fb9fec8d3bba36ef88345e3494ce79ce9441c5442504b?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/bd8737297dedc53a4b9fb9fec8d3bba36ef88345e3494ce79ce9441c5442504b?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/bd8737297dedc53a4b9fb9fec8d3bba36ef88345e3494ce79ce9441c5442504b?s=96&d=mm&r=g","caption":"solobrasil2"},"sameAs":["https:\/\/solobrasid.com"]}]}},"_links":{"self":[{"href":"https:\/\/solobrasid.com\/porta-corta-fogo\/wp-json\/wp\/v2\/posts\/5204","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/solobrasid.com\/porta-corta-fogo\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/solobrasid.com\/porta-corta-fogo\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/solobrasid.com\/porta-corta-fogo\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/solobrasid.com\/porta-corta-fogo\/wp-json\/wp\/v2\/comments?post=5204"}],"version-history":[{"count":1,"href":"https:\/\/solobrasid.com\/porta-corta-fogo\/wp-json\/wp\/v2\/posts\/5204\/revisions"}],"predecessor-version":[{"id":14414,"href":"https:\/\/solobrasid.com\/porta-corta-fogo\/wp-json\/wp\/v2\/posts\/5204\/revisions\/14414"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/solobrasid.com\/porta-corta-fogo\/wp-json\/wp\/v2\/media\/5216"}],"wp:attachment":[{"href":"https:\/\/solobrasid.com\/porta-corta-fogo\/wp-json\/wp\/v2\/media?parent=5204"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/solobrasid.com\/porta-corta-fogo\/wp-json\/wp\/v2\/categories?post=5204"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/solobrasid.com\/porta-corta-fogo\/wp-json\/wp\/v2\/tags?post=5204"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}